{"id":1986,"date":"2021-06-04T08:36:03","date_gmt":"2021-06-04T07:36:03","guid":{"rendered":"https:\/\/llorensgmr.com\/?p=1986"},"modified":"2021-06-04T08:36:03","modified_gmt":"2021-06-04T07:36:03","slug":"llorens-circular-2","status":"publish","type":"post","link":"https:\/\/llorensgmr.com\/es\/sin-categorizar\/llorens-circular-2\/","title":{"rendered":"Llorens|gmr Circular"},"content":{"rendered":"<p>Desde Llorens|gmr\u00a0os presentamos una nueva iniciativa para favorecer la econom\u00eda circular. A partir de ahora ofrecemos un servicio de suministro de sacos y bolsas de basura fabricadas a partir de los residuos de LDPE que recogemos a nuestros clientes. Bolsas fabricadas a partir de bolsas, innovaci\u00f3n y reciclaje, en definitiva el esp\u00edritu de Llorens|gmr.<\/p>\n<p>En la siguiente presentaci\u00f3n os mostramos todos los beneficios de este servicio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1987\" src=\"https:\/\/llorensgmr.com\/wp-content\/uploads\/2021\/06\/ldpe_circular-300x190.jpg\" alt=\"\" width=\"300\" height=\"190\" srcset=\"https:\/\/llorensgmr.com\/wp-content\/uploads\/2021\/06\/ldpe_circular-300x190.jpg 300w, https:\/\/llorensgmr.com\/wp-content\/uploads\/2021\/06\/ldpe_circular-768x486.jpg 768w, https:\/\/llorensgmr.com\/wp-content\/uploads\/2021\/06\/ldpe_circular-700x443.jpg 700w, https:\/\/llorensgmr.com\/wp-content\/uploads\/2021\/06\/ldpe_circular.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Si quieres saber m\u00e1s de nuestra planta de reciclaje de pl\u00e1stico film puedes consultar nuestro apartado en la web:\u00a0<a href=\"https:\/\/llorensgmr.com\/plastico-flexible\/\">https:\/\/llorensgmr.com\/plastico-flexible\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde Llorens|gmr\u00a0os presentamos una nueva iniciativa para favorecer la econom\u00eda circular. A partir de ahora ofrecemos un servicio de suministro de sacos y bolsas de basura fabricadas a partir de los residuos de LDPE que recogemos a nuestros clientes. Bolsas fabricadas a partir de bolsas,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/llorensgmr.com\/es\/wp-json\/wp\/v2\/posts\/1986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/llorensgmr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/llorensgmr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/llorensgmr.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/llorensgmr.com\/es\/wp-json\/wp\/v2\/comments?post=1986"}],"version-history":[{"count":3,"href":"https:\/\/llorensgmr.com\/es\/wp-json\/wp\/v2\/posts\/1986\/revisions"}],"predecessor-version":[{"id":1994,"href":"https:\/\/llorensgmr.com\/es\/wp-json\/wp\/v2\/posts\/1986\/revisions\/1994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/llorensgmr.com\/es\/wp-json\/wp\/v2\/media\/1987"}],"wp:attachment":[{"href":"https:\/\/llorensgmr.com\/es\/wp-json\/wp\/v2\/media?parent=1986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/llorensgmr.com\/es\/wp-json\/wp\/v2\/categories?post=1986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/llorensgmr.com\/es\/wp-json\/wp\/v2\/tags?post=1986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}